{"id":136,"date":"2017-06-28T13:36:34","date_gmt":"2017-06-28T11:36:34","guid":{"rendered":"http:\/\/arkhe.it\/libri\/?post_type=product&#038;p=136"},"modified":"2019-09-16T12:09:13","modified_gmt":"2019-09-16T10:09:13","slug":"rapsodia-della-tensione-efficace","status":"publish","type":"product","link":"https:\/\/www.arkhe.it\/libri\/prodotto\/rapsodia-della-tensione-efficace\/","title":{"rendered":"Rapsodia della tensione efficace"},"content":{"rendered":"<p>Volume realizzato in occasione del quindicesimo anno dalla fondazione dell&#8217;associazione \u201cDeltensemle\u201d, con testi e versi di Elio Peretti e Gianfranco Totani, illustrazioni di Giancarlo Flati e CD allegato con registrazione dei brani eseguiti dal gruppo vocale e strumentale \u201cDeltensemble\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Volume realizzato in occasione del quindicesimo anno dalla fondazione dell&#8217;associazione \u201cDeltensemle\u201d, con testi e versi di Elio Peretti e Gianfranco Totani, illustrazioni di Giancarlo Flati e CD allegato con registrazione [&hellip;]<\/p>\n","protected":false},"featured_media":138,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[67],"product_tag":[],"_links":{"self":[{"href":"https:\/\/www.arkhe.it\/libri\/wp-json\/wp\/v2\/product\/136"}],"collection":[{"href":"https:\/\/www.arkhe.it\/libri\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.arkhe.it\/libri\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arkhe.it\/libri\/wp-json\/wp\/v2\/comments?post=136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arkhe.it\/libri\/wp-json\/wp\/v2\/media\/138"}],"wp:attachment":[{"href":"https:\/\/www.arkhe.it\/libri\/wp-json\/wp\/v2\/media?parent=136"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.arkhe.it\/libri\/wp-json\/wp\/v2\/product_cat?post=136"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.arkhe.it\/libri\/wp-json\/wp\/v2\/product_tag?post=136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}