{"id":230,"date":"2017-12-19T18:14:18","date_gmt":"2017-12-19T17:14:18","guid":{"rendered":"http:\/\/arkhe.it\/libri\/?post_type=product&#038;p=230"},"modified":"2018-01-12T17:15:36","modified_gmt":"2018-01-12T16:15:36","slug":"il-demone-delle-nfrelleche","status":"publish","type":"product","link":"https:\/\/www.arkhe.it\/libri\/prodotto\/il-demone-delle-nfrelleche\/","title":{"rendered":"Il demone delle &#8216;nfrelleche"},"content":{"rendered":"<p>L\u2019esistenza di una persona che vuole dare un senso, una logica ed un significato a ci\u00f2 che fa e che ha fatto in passato. Giunto al traguardo della pensione decider\u00e0 dunque di lavorare su se stesso, rielaborando il vissuto in maniera utile per il prosieguo del cammino. Un insieme di racconti che spaziano dalle cronache familiari e paesane alla vita professionale ed umana fino all\u2019attualit\u00e0 presente, con tutti i risvolti di un itinerario tormentato e difficile, come per tanti poveri cristi. Il \u201cDemone\u201d del titolo \u00e8 assimilabile alle figure mitologiche di Omero, numi tutelari che reggevano il destino di una persona nel bene e nel male. Il termine dialettale \u2019nfrelleche invece, \u00e8 quello che spinge la vita dell\u2019uomo moderno a ritmo frenetico.<\/p>\n<p><em>\u2019nfrelleche: termine dialettale con diversi significati i pi\u00f9 comuni sono due:<br \/>\na) riferite ai bambini sono le cos\u00ec dette marachelle, dispetti;<br \/>\nb) riferite agli adulti assumono il significato di insoddisfazione, ricerca del\u00a0meglio, stato di agitazione con determinazioni psico-fisiche.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019esistenza di una persona che vuole dare un senso, una logica ed un significato a ci\u00f2 che fa e che ha fatto in passato. Giunto al traguardo della pensione decider\u00e0 [&hellip;]<\/p>\n","protected":false},"featured_media":231,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[20],"product_tag":[],"_links":{"self":[{"href":"https:\/\/www.arkhe.it\/libri\/wp-json\/wp\/v2\/product\/230"}],"collection":[{"href":"https:\/\/www.arkhe.it\/libri\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.arkhe.it\/libri\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arkhe.it\/libri\/wp-json\/wp\/v2\/comments?post=230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arkhe.it\/libri\/wp-json\/wp\/v2\/media\/231"}],"wp:attachment":[{"href":"https:\/\/www.arkhe.it\/libri\/wp-json\/wp\/v2\/media?parent=230"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.arkhe.it\/libri\/wp-json\/wp\/v2\/product_cat?post=230"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.arkhe.it\/libri\/wp-json\/wp\/v2\/product_tag?post=230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}